{"id":112448,"date":"2025-05-29T11:38:07","date_gmt":"2025-05-29T10:38:07","guid":{"rendered":"https:\/\/www.univ-soukahras.dz\/fr\/?p=112448"},"modified":"2025-06-11T08:40:29","modified_gmt":"2025-06-11T07:40:29","slug":"la-journee-detudes-aid-2025-se-tiendra-a-luniversite-de-souk-ahras-le-06-novembre-2025","status":"publish","type":"post","link":"https:\/\/univ-soukahras.dz\/ar\/actualites\/all-faculties\/st\/la-journee-detudes-aid-2025-se-tiendra-a-luniversite-de-souk-ahras-le-06-novembre-2025","title":{"rendered":"Journ\u00e9e d\u2019\u00e9tudes L&#8217;intelligence artificielle et ses applications dans les domaines de g\u00e9nie civil et d&#8217;hydraulique &#8221; d\u00e9veloppement durable, environnement et \u00e9nergies renouvelables AID 2025 , le 06 novembre 2025."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>&nbsp;&nbsp;L&#8217;intelligence artificielle et ses applications dans les domaines de g\u00e9nie civil et d\u2019hydraulique<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00ab&nbsp;<a>d\u00e9veloppement durable, environnement et \u00e9nergies renouvelables&nbsp;<\/a>\u00bb<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;&#8211; AID 2025<\/strong>&#8220;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La journ\u00e9e d\u2019\u00e9tudes AID 2025 se tiendra \u00e0 l\u2019Universit\u00e9 de Souk-ahras, le 06 novembre 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons le plaisir de vous inviter \u00e0 participer \u00e0 cet \u00e9v\u00e9nement scientifique, qui r\u00e9unira des chercheurs, des experts du g\u00e9nie civil et de l\u2019hydraulique, ainsi que des professionnels du secteur.<br>Cette rencontre vise \u00e0 explorer les interactions entre recherche acad\u00e9mique et pratiques professionnelles, autour des grands enjeux actuels.<br>Une attention particuli\u00e8re sera port\u00e9e aux applications concr\u00e8tes de l\u2019intelligence artificielle, telles que l\u2019optimisation de la gestion des r\u00e9seaux hydrauliques, la mod\u00e9lisation pr\u00e9dictive des structures, la surveillance automatis\u00e9e des infrastructures, ou encore l\u2019analyse des donn\u00e9es climatiques pour la planification urbaine.<br>L\u2019objectif est de favoriser l\u2019\u00e9mergence de solutions innovantes, \u00e0 la crois\u00e9e de la science et de l\u2019ing\u00e9nierie appliqu\u00e9e.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object aria-label=\"PDF embed\" data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden><\/object><a id=\"wp-block-file--media-1f1ec092-0f3d-437f-9fb0-77924b5e928d\" href=\"\/wpuploads\/\/2025\/05\/depliant-journee-AID-2025-V5-anglais2-2.pdf\">d\u00e9pliant journ\u00e9e AID 2025 V5 anglais2<\/a><a href=\"\/wpuploads\/\/2025\/05\/depliant-journee-AID-2025-V5-anglais2-2.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-1f1ec092-0f3d-437f-9fb0-77924b5e928d\">Download<\/a><\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object aria-label=\"PDF embed\" data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden><\/object><a id=\"wp-block-file--media-afc7b68d-bdf2-421a-be71-13ddf0f3985c\" href=\"\/wpuploads\/\/2025\/05\/depliant-journee-AID-2025-V5-francais-12-2.pdf\">d\u00e9pliant journ\u00e9e AID 2025 V5 fran\u00e7ais (1)2<\/a><a href=\"\/wpuploads\/\/2025\/05\/depliant-journee-AID-2025-V5-francais-12-2.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-afc7b68d-bdf2-421a-be71-13ddf0f3985c\">Download<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-ccdd27b1-e2d9-4273-b60d-7f69f6f0d785\" href=\"\/wpuploads\/\/2025\/05\/template_poster_AID2025-1.pptx\">template_poster_AID2025- (1)<\/a><a href=\"\/wpuploads\/\/2025\/05\/template_poster_AID2025-1.pptx\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-ccdd27b1-e2d9-4273-b60d-7f69f6f0d785\">Download<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-d5f00c64-1c62-4723-98d9-992fe9cf1187\" href=\"\/wpuploads\/\/2025\/05\/Format-du-resume-etendu_AID2025-1.docx\">Format-du-resume-etendu_AID2025 (1)<\/a><a href=\"\/wpuploads\/\/2025\/05\/Format-du-resume-etendu_AID2025-1.docx\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-d5f00c64-1c62-4723-98d9-992fe9cf1187\">Download<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-987f1b5f-e19d-49d3-80d7-bbc74f0119ab\" href=\"\/wpuploads\/\/2025\/05\/Fiche-dinscription_AID2025-1.docx\">Fiche-dinscription_AID2025- (1)<\/a><a href=\"\/wpuploads\/\/2025\/05\/Fiche-dinscription_AID2025-1.docx\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-987f1b5f-e19d-49d3-80d7-bbc74f0119ab\">Download<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;&nbsp;L&#8217;intelligence artificielle et ses applications dans les domaines de g\u00e9nie civil et d\u2019hydraulique \u00ab&nbsp;d\u00e9veloppement durable, environnement et \u00e9nergies renouvelables&nbsp;\u00bb &nbsp;&#8211; [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,7],"tags":[],"class_list":["post-112448","post","type-post","status-publish","format-standard","hentry","category-fr","category-st"],"_links":{"self":[{"href":"https:\/\/univ-soukahras.dz\/ar\/wp-json\/wp\/v2\/posts\/112448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/univ-soukahras.dz\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/univ-soukahras.dz\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/univ-soukahras.dz\/ar\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/univ-soukahras.dz\/ar\/wp-json\/wp\/v2\/comments?post=112448"}],"version-history":[{"count":4,"href":"https:\/\/univ-soukahras.dz\/ar\/wp-json\/wp\/v2\/posts\/112448\/revisions"}],"predecessor-version":[{"id":113008,"href":"https:\/\/univ-soukahras.dz\/ar\/wp-json\/wp\/v2\/posts\/112448\/revisions\/113008"}],"wp:attachment":[{"href":"https:\/\/univ-soukahras.dz\/ar\/wp-json\/wp\/v2\/media?parent=112448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/univ-soukahras.dz\/ar\/wp-json\/wp\/v2\/categories?post=112448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/univ-soukahras.dz\/ar\/wp-json\/wp\/v2\/tags?post=112448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}