{"id":46701,"date":"2021-04-11T09:46:16","date_gmt":"2021-04-11T09:46:16","guid":{"rendered":"http:\/\/www.univ-soukahras.dz\/fr\/?p=46701"},"modified":"2021-04-12T12:36:56","modified_gmt":"2021-04-12T12:36:56","slug":"energytech-shes-in-tech-challenge","status":"publish","type":"post","link":"https:\/\/univ-soukahras.dz\/en\/actualites\/energytech-shes-in-tech-challenge","title":{"rendered":"EnergyTECH (She&#8217;s In TECH Challenge)"},"content":{"rendered":"<p>L&#8217;\u00e9nergie au c\u0153ur du Marathon Technologique f\u00e9minin qui a \u00e9t\u00e9 lanc\u00e9 le 31 mars par la startup NafsiyaTECH sous le haut patronage du Ministre D\u00e9l\u00e9gu\u00e9 \u200eAupr\u00e8s du Premier Ministre Charg\u00e9 de l&#8217;Economie de la Connaissance et des Startups<br \/>\nLes acteurs de l&#8217;\u00e9nergie sont invit\u00e9s \u00e0 s&#8217;inscrire et partager cet \u00e9v\u00e8nement avec les alg\u00e9riennes porteuses d&#8217;id\u00e9es et de projets dans les 6 th\u00e9matiques \u200epropos\u00e9es \u00e0 savoir:\u200e<br \/>\n\u200e1.\u200e \u200e\u200e EnergyTECH ( solutions tech dans le domaine de l\u2019\u00e9nergie Solaire, eolienne, etc. )\u200e<br \/>\n\u200e2.\u200e \u200e\u00a0<b>FinTECH \/ InsurTECH\u00a0<\/b>( e-finance , e-banque, e-assurance, etc..)\u200e<br \/>\n\u200e3.\u200e\u00a0<b>DiasporaTECH\u00a0<\/b>( Solutions tech mis au service de la diaspora pour renforcer ses liens \u00a0\u200epersonnels, \u200eprofessionnels et financiers avec sa famille, ses \u200eproches et son pays. Les \u200ed\u00e9veloppeuses de ces \u200esolutions seront des r\u00e9sidentes en Alg\u00e9rie ou \u00e0 l&#8217;\u00e9tranger )\u200e<br \/>\n\u200e4.\u200e \u200e<b>Transport TECH\u00a0<\/b>( \u00a0transport terrestre &#8211; a\u00e9rien-maritime- ferroviaire , e-voiture , e-bicyclette.) \u200e<br \/>\n\u200e5.\u200e\u00a0<b>\u200e CultureTECH\u00a0<\/b>( e-Mus\u00e9es, e-th\u00e9\u00e2tres, e-musique, e-patrimoine (mat\u00e9riel et non mat\u00e9riel ect..) e-\u200ephotographie)\u200e<br \/>\n\u200e6.\u200e\u00a0<b>HealthTECH\u00a0<\/b>&amp;\u00a0<b>Mental HealthTECH<\/b>\u00a0( Sant\u00e9 \u2013e-Sant\u00e9\/ Sant\u00e9 mentale \u2013 e-sant\u00e9 mentale)\u200e<br \/>\n\u200e07 laur\u00e9ates seront choisies pour avoir les premiers prix et un accompagnement dans un incubateur sp\u00e9cialis\u00e9 suivant la th\u00e9matique d&#8217;inscription.\u200e<\/p>\n<p><strong><span style=\"color: #ff0000;\">Dernier d\u00e9lai d&#8217;inscription le 25 Avril 2021<\/span><\/strong><\/p>\n<p><b>LE FORMULAIRE D&#8217;INSCRIPTION : \u200e<\/b><\/p>\n<p><a href=\"https:\/\/forms.nafsiyatech.com\/\" target=\"_blank\">https:\/\/forms.nafsiyatech.com<\/a>\u00a0\u200e<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9nergie au c\u0153ur du Marathon Technologique f\u00e9minin qui a \u00e9t\u00e9 lanc\u00e9 le 31 mars par la startup NafsiyaTECH sous le [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":46703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,44],"tags":[],"class_list":["post-46701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-relex"],"_links":{"self":[{"href":"https:\/\/univ-soukahras.dz\/en\/wp-json\/wp\/v2\/posts\/46701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/univ-soukahras.dz\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/univ-soukahras.dz\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/univ-soukahras.dz\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/univ-soukahras.dz\/en\/wp-json\/wp\/v2\/comments?post=46701"}],"version-history":[{"count":2,"href":"https:\/\/univ-soukahras.dz\/en\/wp-json\/wp\/v2\/posts\/46701\/revisions"}],"predecessor-version":[{"id":46743,"href":"https:\/\/univ-soukahras.dz\/en\/wp-json\/wp\/v2\/posts\/46701\/revisions\/46743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/univ-soukahras.dz\/en\/wp-json\/wp\/v2\/media\/46703"}],"wp:attachment":[{"href":"https:\/\/univ-soukahras.dz\/en\/wp-json\/wp\/v2\/media?parent=46701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/univ-soukahras.dz\/en\/wp-json\/wp\/v2\/categories?post=46701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/univ-soukahras.dz\/en\/wp-json\/wp\/v2\/tags?post=46701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}